{"id":2609,"date":"2024-05-10T19:02:43","date_gmt":"2024-05-10T17:02:43","guid":{"rendered":"https:\/\/www.olivertreutlein.com\/newsletter-registration\/"},"modified":"2024-09-23T11:13:52","modified_gmt":"2024-09-23T09:13:52","slug":"newsletter-registration","status":"publish","type":"page","link":"https:\/\/www.olivertreutlein.com\/en\/newsletter-registration\/","title":{"rendered":"Newsletter-Registration"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1>Newsletter-Registration<\/h1>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2684-o1\" lang=\"de-DE\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2609#wpcf7-f2684-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2684\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2684-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Name\/Company*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Your Email address*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><span id=\"wpcf7-6a980018cc555-wrapper\" class=\"wpcf7-form-control-wrap first-name-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a980018cc555-field\" class=\"hp-message\">Bitte lasse dieses Feld leer.<\/label><input id=\"wpcf7-6a980018cc555-field\"  placeholder=\"Vorname\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"first-name\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span><span id=\"wpcf7-6a980018cc5cf-wrapper\" class=\"wpcf7-form-control-wrap last-name-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a980018cc5cf-field\" class=\"hp-message\">Bitte lasse dieses Feld leer.<\/label><input id=\"wpcf7-6a980018cc5cf-field\"  placeholder=\"Nachname\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"last-name\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Register now\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Newsletter-Registration Name\/Company* Your Email address* Bitte lasse dieses Feld leer.Bitte lasse dieses Feld leer.","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.olivertreutlein.com\/en\/wp-json\/wp\/v2\/pages\/2609"}],"collection":[{"href":"https:\/\/www.olivertreutlein.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.olivertreutlein.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.olivertreutlein.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olivertreutlein.com\/en\/wp-json\/wp\/v2\/comments?post=2609"}],"version-history":[{"count":2,"href":"https:\/\/www.olivertreutlein.com\/en\/wp-json\/wp\/v2\/pages\/2609\/revisions"}],"predecessor-version":[{"id":2687,"href":"https:\/\/www.olivertreutlein.com\/en\/wp-json\/wp\/v2\/pages\/2609\/revisions\/2687"}],"wp:attachment":[{"href":"https:\/\/www.olivertreutlein.com\/en\/wp-json\/wp\/v2\/media?parent=2609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}